{"id":2831,"date":"2021-01-30T18:04:03","date_gmt":"2021-01-30T18:04:03","guid":{"rendered":"http:\/\/arthistory.tsu.ge\/murals\/?post_type=galleries&#038;p=2831"},"modified":"2021-02-17T09:44:22","modified_gmt":"2021-02-17T09:44:22","slug":"%e1%83%ae%e1%83%90%e1%83%ae%e1%83%a3%e1%83%9a%e1%83%98-%e1%83%a6%e1%83%9b%e1%83%a0%e1%83%97%e1%83%98%e1%83%a1%e1%83%9b%e1%83%a8%e1%83%9d%e1%83%91%e1%83%9a%e1%83%98%e1%83%a1-%e1%83%a1%e1%83%90","status":"publish","type":"galleries","link":"https:\/\/arthistory.tsu.ge\/murals\/galleries\/%e1%83%ae%e1%83%90%e1%83%ae%e1%83%a3%e1%83%9a%e1%83%98-%e1%83%a6%e1%83%9b%e1%83%a0%e1%83%97%e1%83%98%e1%83%a1%e1%83%9b%e1%83%a8%e1%83%9d%e1%83%91%e1%83%9a%e1%83%98%e1%83%a1-%e1%83%a1%e1%83%90\/","title":{"rendered":"\u10ee\u10d0\u10ee\u10e3\u10da\u10d8, \u10e6\u10db\u10e0\u10d7\u10d8\u10e1\u10db\u10e8\u10dd\u10d1\u10da\u10d8\u10e1 \u10e1\u10d0\u10d9\u10d0\u10d7\u10d4\u10d3\u10e0\u10dd \u10e2\u10d0\u10eb\u10d0\u10e0\u10d8"},"content":{"rendered":"<div class=\"fat-maika-container isotope fat-maika-shortcode-2550 fat-lightbox-gallery disable-download show-thumbnail root-filter\" data-maika-col=\"4\" data-item-per-page=\"\"\r\n     data-animation=\"none\"\r\n     data-animation-duration=\"200\">\r\n    <div class=\"fat-maika-category-filter cat-skin-01 text-left\">\r\n    <ul class=\"fat-maika-category\">\r\n                    <li>\r\n                <a href=\"javascript:void(0)\"\r\n                   data-category=\"j1_1\">\u10e7\u10d5\u10d4\u10da\u10d0<\/a>\r\n            <\/li>\r\n                <li class=\"cat-item\"><a href=\"javascript:void(0)\" class=\"\" data-category=\"j1_2\" data-parent=\"j1_1\">\u10d0\u10e0\u10e5\u10d8\u10e2\u10d4\u10e5\u10e2\u10e3\u10e0\u10d0<\/a><\/li><li class=\"cat-item\"><a href=\"javascript:void(0)\" class=\"\" data-category=\"j1_3\" data-parent=\"j1_1\">\u10db\u10dd\u10ee\u10d0\u10e2\u10e3\u10da\u10dd\u10d1\u10d0<\/a><\/li><li class=\"cat-item\"><a href=\"javascript:void(0)\" class=\"\" data-category=\"j1_4\" data-parent=\"j1_1\">\u10e1\u10e5\u10d4\u10db\u10d4\u10d1\u10d8<\/a><\/li>    <\/ul>\r\n        <\/div>\r\n    <div class=\"fat-maika-listing masonry fat-padding-10\">\r\n        <div class=\"fat-gallery-item fat-col-sm-6 fat-col-xs-12 fat-col-md-4 item-skin-03  j1_2 \" data-img-id=\"3067\">\r\n    <div class=\"fat-maika-item-inner\" data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khahkhuli-800x533.jpg\">\r\n                    <img alt=\"\u10ee\u10d0\u10ee\u10e3\u10da\u10d8, \u10e6\u10db\u10e0\u10d7\u10d8\u10e1\u10db\u10e8\u10dd\u10d1\u10da\u10d8\u10e1 \u10e1\u10d0\u10d9\u10d0\u10d7\u10d4\u10d3\u10e0\u10dd \u10e2\u10d0\u10eb\u10d0\u10e0\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khahkhuli-800x533.jpg\"\r\n                 width=\"800\" height=\"533\">\r\n                <div class=\"fat-maika-overlay maika-tran-05\">\r\n\r\n                    <a href=\"javascript:void(0)\" class=\"view-gallery\"\r\n                       data-title=\"\u10ee\u10d0\u10ee\u10e3\u10da\u10d8, \u10e6\u10db\u10e0\u10d7\u10d8\u10e1\u10db\u10e8\u10dd\u10d1\u10da\u10d8\u10e1 \u10e1\u10d0\u10d9\u10d0\u10d7\u10d4\u10d3\u10e0\u10dd \u10e2\u10d0\u10eb\u10d0\u10e0\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8\"\r\n                       data-desc=\"\"\r\n                       data-img=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khahkhuli.jpg\"\r\n                       data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khahkhuli-800x533.jpg\"\r\n                       data-width=\"900\"\r\n                       data-height=\"600\"\r\n                    >\r\n<img class=\"hidden\" alt=\"\u10ee\u10d0\u10ee\u10e3\u10da\u10d8, \u10e6\u10db\u10e0\u10d7\u10d8\u10e1\u10db\u10e8\u10dd\u10d1\u10da\u10d8\u10e1 \u10e1\u10d0\u10d9\u10d0\u10d7\u10d4\u10d3\u10e0\u10dd \u10e2\u10d0\u10eb\u10d0\u10e0\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khahkhuli-800x533.jpg\"\r\nwidth=\"800\" height=\"533\">\r\n\r\n            <div class=\"fat-maika-info-wrap\">\r\n                <div class=\"fat-maika-title  maika-tran-05\">\r\n                            \u10ee\u10d0\u10ee\u10e3\u10da\u10d8, \u10e6\u10db\u10e0\u10d7\u10d8\u10e1\u10db\u10e8\u10dd\u10d1\u10da\u10d8\u10e1 \u10e1\u10d0\u10d9\u10d0\u10d7\u10d4\u10d3\u10e0\u10dd \u10e2\u10d0\u10eb\u10d0\u10e0\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8                <\/div>\r\n                <div class=\"fat-maika-category  maika-tran-05\">\r\n                    \u10d0\u10e0\u10e5\u10d8\u10e2\u10d4\u10e5\u10e2\u10e3\u10e0\u10d0                <\/div>\r\n            <\/div>\r\n                    <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"fat-gallery-item fat-col-sm-6 fat-col-xs-12 fat-col-md-4 item-skin-03  j1_3 \" data-img-id=\"3068\">\r\n    <div class=\"fat-maika-item-inner\" data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-01-800x533.jpg\">\r\n                    <img alt=\"\u10d2\u10e3\u10db\u10d1\u10d0\u10d7\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-01-800x533.jpg\"\r\n                 width=\"800\" height=\"533\">\r\n                <div class=\"fat-maika-overlay maika-tran-05\">\r\n\r\n                    <a href=\"javascript:void(0)\" class=\"view-gallery\"\r\n                       data-title=\"\u10d2\u10e3\u10db\u10d1\u10d0\u10d7\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8\"\r\n                       data-desc=\"\"\r\n                       data-img=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-01.jpg\"\r\n                       data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-01-800x533.jpg\"\r\n                       data-width=\"900\"\r\n                       data-height=\"600\"\r\n                    >\r\n<img class=\"hidden\" alt=\"\u10d2\u10e3\u10db\u10d1\u10d0\u10d7\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-01-800x533.jpg\"\r\nwidth=\"800\" height=\"533\">\r\n\r\n            <div class=\"fat-maika-info-wrap\">\r\n                <div class=\"fat-maika-title  maika-tran-05\">\r\n                            \u10d2\u10e3\u10db\u10d1\u10d0\u10d7\u10d8, \u10e1\u10d0\u10d4\u10e0\u10d7\u10dd \u10ee\u10d4\u10d3\u10d8                <\/div>\r\n                <div class=\"fat-maika-category  maika-tran-05\">\r\n                    \u10db\u10dd\u10ee\u10d0\u10e2\u10e3\u10da\u10dd\u10d1\u10d0                <\/div>\r\n            <\/div>\r\n                    <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"fat-gallery-item fat-col-sm-6 fat-col-xs-12 fat-col-md-4 item-skin-03  j1_3 \" data-img-id=\"3069\">\r\n    <div class=\"fat-maika-item-inner\" data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-02-800x1200.jpg\">\r\n                    <img alt=\"\u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10db\u10dd\u10ea\u10d8\u10e5\u10e3\u10da\u10d7\u10d0 \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-02-800x1200.jpg\"\r\n                 width=\"800\" height=\"1200\">\r\n                <div class=\"fat-maika-overlay maika-tran-05\">\r\n\r\n                    <a href=\"javascript:void(0)\" class=\"view-gallery\"\r\n                       data-title=\"\u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10db\u10dd\u10ea\u10d8\u10e5\u10e3\u10da\u10d7\u10d0 \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0\"\r\n                       data-desc=\"\"\r\n                       data-img=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-02.jpg\"\r\n                       data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-02-800x1200.jpg\"\r\n                       data-width=\"900\"\r\n                       data-height=\"600\"\r\n                    >\r\n<img class=\"hidden\" alt=\"\u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10db\u10dd\u10ea\u10d8\u10e5\u10e3\u10da\u10d7\u10d0 \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-02-800x1200.jpg\"\r\nwidth=\"800\" height=\"1200\">\r\n\r\n            <div class=\"fat-maika-info-wrap\">\r\n                <div class=\"fat-maika-title  maika-tran-05\">\r\n                            \u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10db\u10dd\u10ea\u10d8\u10e5\u10e3\u10da\u10d7\u10d0 \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0                <\/div>\r\n                <div class=\"fat-maika-category  maika-tran-05\">\r\n                    \u10db\u10dd\u10ee\u10d0\u10e2\u10e3\u10da\u10dd\u10d1\u10d0                <\/div>\r\n            <\/div>\r\n                    <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"fat-gallery-item fat-col-sm-6 fat-col-xs-12 fat-col-md-4 item-skin-03  j1_3 \" data-img-id=\"3070\">\r\n    <div class=\"fat-maika-item-inner\" data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-03-800x533.jpg\">\r\n                    <img alt=\"\u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10dc\u10d8\u10e8\u10d4\u10d1\u10d8\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-03-800x533.jpg\"\r\n                 width=\"800\" height=\"533\">\r\n                <div class=\"fat-maika-overlay maika-tran-05\">\r\n\r\n                    <a href=\"javascript:void(0)\" class=\"view-gallery\"\r\n                       data-title=\"\u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10dc\u10d8\u10e8\u10d4\u10d1\u10d8\"\r\n                       data-desc=\"\"\r\n                       data-img=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-03.jpg\"\r\n                       data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-03-800x533.jpg\"\r\n                       data-width=\"900\"\r\n                       data-height=\"600\"\r\n                    >\r\n<img class=\"hidden\" alt=\"\u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10dc\u10d8\u10e8\u10d4\u10d1\u10d8\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-03-800x533.jpg\"\r\nwidth=\"800\" height=\"533\">\r\n\r\n            <div class=\"fat-maika-info-wrap\">\r\n                <div class=\"fat-maika-title  maika-tran-05\">\r\n                            \u10e1\u10d0\u10d9\u10e3\u10e0\u10d7\u10ee\u10d4\u10d5\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10dc\u10d8\u10e8\u10d4\u10d1\u10d8                <\/div>\r\n                <div class=\"fat-maika-category  maika-tran-05\">\r\n                    \u10db\u10dd\u10ee\u10d0\u10e2\u10e3\u10da\u10dd\u10d1\u10d0                <\/div>\r\n            <\/div>\r\n                    <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"fat-gallery-item fat-col-sm-6 fat-col-xs-12 fat-col-md-4 item-skin-03  j1_3 \" data-img-id=\"3071\">\r\n    <div class=\"fat-maika-item-inner\" data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-04-800x533.jpg\">\r\n                    <img alt=\"\u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10e1\u10d0\u10d9\u10e2\u10d8\u10e2\u10dd\u10e0\u10dd \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-04-800x533.jpg\"\r\n                 width=\"800\" height=\"533\">\r\n                <div class=\"fat-maika-overlay maika-tran-05\">\r\n\r\n                    <a href=\"javascript:void(0)\" class=\"view-gallery\"\r\n                       data-title=\"\u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10e1\u10d0\u10d9\u10e2\u10d8\u10e2\u10dd\u10e0\u10dd \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0\"\r\n                       data-desc=\"\"\r\n                       data-img=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-04.jpg\"\r\n                       data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-04-800x533.jpg\"\r\n                       data-width=\"900\"\r\n                       data-height=\"600\"\r\n                    >\r\n<img class=\"hidden\" alt=\"\u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10e1\u10d0\u10d9\u10e2\u10d8\u10e2\u10dd\u10e0\u10dd \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-04-800x533.jpg\"\r\nwidth=\"800\" height=\"533\">\r\n\r\n            <div class=\"fat-maika-info-wrap\">\r\n                <div class=\"fat-maika-title  maika-tran-05\">\r\n                            \u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10d3\u10d0\u10e1\u10d0\u10d5\u10da\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10e9\u10e0\u10d3\u10d8\u10da\u10dd\u10d4\u10d7 \u10db\u10dd\u10dc\u10d0\u10d9\u10d5\u10d4\u10d7\u10d8, \u10e1\u10d0\u10d9\u10e2\u10d8\u10e2\u10dd\u10e0\u10dd \u10d2\u10d0\u10db\u10dd\u10e1\u10d0\u10ee\u10e3\u10da\u10d4\u10d1\u10d0                <\/div>\r\n                <div class=\"fat-maika-category  maika-tran-05\">\r\n                    \u10db\u10dd\u10ee\u10d0\u10e2\u10e3\u10da\u10dd\u10d1\u10d0                <\/div>\r\n            <\/div>\r\n                    <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"fat-gallery-item fat-col-sm-6 fat-col-xs-12 fat-col-md-4 item-skin-03  j1_3 \" data-img-id=\"3072\">\r\n    <div class=\"fat-maika-item-inner\" data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-05-800x499.jpg\">\r\n                    <img alt=\"\u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10d8\u10d4\u10e0\u10e3\u10e1\u10d0\u10da\u10d8\u10db\u10d0\u10d3 \u10e8\u10d4\u10e1\u10d5\u10da\u10d0 (\u10da. \u10d2\u10e3\u10d3\u10d8\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10d0\u10e1\u10da\u10d8)\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-05-800x499.jpg\"\r\n                 width=\"800\" height=\"499\">\r\n                <div class=\"fat-maika-overlay maika-tran-05\">\r\n\r\n                    <a href=\"javascript:void(0)\" class=\"view-gallery\"\r\n                       data-title=\"\u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10d8\u10d4\u10e0\u10e3\u10e1\u10d0\u10da\u10d8\u10db\u10d0\u10d3 \u10e8\u10d4\u10e1\u10d5\u10da\u10d0 (\u10da. \u10d2\u10e3\u10d3\u10d8\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10d0\u10e1\u10da\u10d8)\"\r\n                       data-desc=\"\"\r\n                       data-img=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-05.jpg\"\r\n                       data-thumb=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-05-800x499.jpg\"\r\n                       data-width=\"900\"\r\n                       data-height=\"600\"\r\n                    >\r\n<img class=\"hidden\" alt=\"\u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10d8\u10d4\u10e0\u10e3\u10e1\u10d0\u10da\u10d8\u10db\u10d0\u10d3 \u10e8\u10d4\u10e1\u10d5\u10da\u10d0 (\u10da. \u10d2\u10e3\u10d3\u10d8\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10d0\u10e1\u10da\u10d8)\" src=\"https:\/\/arthistory.tsu.ge\/murals\/wp-content\/uploads\/2021\/02\/Khakhuli-05-800x499.jpg\"\r\nwidth=\"800\" height=\"499\">\r\n\r\n            <div class=\"fat-maika-info-wrap\">\r\n                <div class=\"fat-maika-title  maika-tran-05\">\r\n                            \u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10db\u10d9\u10da\u10d0\u10d5\u10d8, \u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10d9\u10d4\u10d3\u10d4\u10da\u10d8, \u10d8\u10d4\u10e0\u10e3\u10e1\u10d0\u10da\u10d8\u10db\u10d0\u10d3 \u10e8\u10d4\u10e1\u10d5\u10da\u10d0 (\u10da. \u10d2\u10e3\u10d3\u10d8\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10d0\u10e1\u10da\u10d8)                <\/div>\r\n                <div class=\"fat-maika-category  maika-tran-05\">\r\n                    \u10db\u10dd\u10ee\u10d0\u10e2\u10e3\u10da\u10dd\u10d1\u10d0                <\/div>\r\n            <\/div>\r\n                    <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n    <\/div>\r\n    <\/div><style type='text\/css' id=\"fat-portfolio-custom-css-2550\">\r\n    \/** category filter **\/\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter li a {\r\n        font-size: 14px;\r\n        text-transform: none;\r\n        color: #343434;\r\n        -webkit-transition: all 0.3s;\r\n        -moz-transition: all 0.3s;\r\n        -ms-transition: all 0.3s;\r\n        -o-transition: all 0.3s;\r\n        transition: all 0.3s;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter.cat-skin-03  ul.fat-maika-category > li > span.filter-count,\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter li a.active,\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter li a:hover {\r\n        color: #343434;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter  li > a{\r\n        background-color: #f1f1f1;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter  ul.sub-cat li > a{\r\n        background-color: #fff;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter li > a.active,\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter  li > a:hover{\r\n       background-color: #faa71a !important;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter.cat-skin-03  ul.fat-maika-category > li > span.filter-count,\r\n    .fat-maika-shortcode-2550 .fat-maika-category-filter.cat-skin-03  ul.fat-maika-category > li > span.filter-count:before{\r\n        background-color: #faa71a !important;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-overlay {\r\n        background-color: rgba(0,0,0,0.7);\r\n    }\r\n    \/** title and category *\/\r\n    .fat-maika-shortcode-2550 .fat-maika-title,\r\n    .fat-maika-shortcode-2550 .fat-maika-title a,\r\n    .fat-maika-shortcode-2550 .fat-maika-title a:active,\r\n    .fat-maika-shortcode-2550 .fat-maika-title a:focus{\r\n        color: #ffffff;\r\n        font-size: 16px;\r\n        text-transform: none;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-title:hover,\r\n    .fat-maika-shortcode-2550 .fat-maika-title:hover a,\r\n    .fat-maika-shortcode-2550 .fat-maika-title:hover a:active,\r\n    .fat-maika-shortcode-2550 .fat-maika-title:hover a:focus{\r\n        color: #eeee22;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category{\r\n        color: #dd9933;\r\n        font-size: 14px;\r\n        text-transform: none;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-category:hover{\r\n        color: #dd9933;\r\n    }\r\n    \/** icon *\/\r\n    .fat-maika-shortcode-2550 .fat-maika-icon a{\r\n        background-color: rgba(0,0,0,0.7);\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-icon a.fat-maika-link-icon,\r\n    .fat-maika-shortcode-2550 .fat-maika-icon a.view-gallery{\r\n        color: #dd9933;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-icon a:after,\r\n    .fat-maika-shortcode-2550 .fat-maika-icon a:before{\r\n        background-color: #dd9933;\r\n    }\r\n    \/** paging *\/\r\n    .fat-maika-shortcode-2550 .fat-maika-paging-container.load-more a{\r\n        color: #fff;\r\n        background-color: #343434;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-paging-container.load-more a:hover{\r\n        color: #343434;\r\n        background-color: #fff;\r\n    }\r\n\r\n    .fat-maika-shortcode-2550 .fat-maika-listing.owl-carousel .owl-dots .owl-dot span{\r\n        background-color: #ddd;\r\n    }\r\n    .fat-maika-shortcode-2550 .fat-maika-listing.owl-carousel .owl-dots .owl-dot.active span,\r\n    .fat-maika-shortcode-2550 .fat-maika-listing.owl-carousel .owl-dots .owl-dot:hover span{\r\n          background-color: #faa71a;\r\n    }\r\n    <\/style>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":3435,"menu_order":0,"template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/arthistory.tsu.ge\/murals\/wp-json\/wp\/v2\/galleries\/2831"}],"collection":[{"href":"https:\/\/arthistory.tsu.ge\/murals\/wp-json\/wp\/v2\/galleries"}],"about":[{"href":"https:\/\/arthistory.tsu.ge\/murals\/wp-json\/wp\/v2\/types\/galleries"}],"author":[{"embeddable":true,"href":"https:\/\/arthistory.tsu.ge\/murals\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arthistory.tsu.ge\/murals\/wp-json\/wp\/v2\/media\/3435"}],"wp:attachment":[{"href":"https:\/\/arthistory.tsu.ge\/murals\/wp-json\/wp\/v2\/media?parent=2831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}